{"id":13208,"date":"2024-05-07T02:07:12","date_gmt":"2024-05-07T02:07:12","guid":{"rendered":"https:\/\/www.physio-network.com\/fr\/blog\/"},"modified":"2024-05-07T02:07:12","modified_gmt":"2024-05-07T02:07:12","slug":"pourquoi-la-kinesitherapie-ne-fonctionne-t-elle-pas-chez-certains-patients-et-comment-minimiser-cet-echec","status":"publish","type":"post","link":"https:\/\/www.physio-network.com\/fr\/blog\/pourquoi-la-kinesitherapie-ne-fonctionne-t-elle-pas-chez-certains-patients-et-comment-minimiser-cet-echec\/","title":{"rendered":"Pourquoi la kin\u00e9sith\u00e9rapie ne fonctionne-t-elle pas chez certains patients et comment minimiser cet \u00e9chec ?"},"content":{"rendered":"<p class=\"text\">En d\u00e9but d&rsquo;ann\u00e9e, j&rsquo;ai lu un excellent travail d&rsquo;Adam Meakins sur le concept d&rsquo;\u00e9chec des patients en kin\u00e9sith\u00e9rapie (1). Ce travail \u00e9tait excellent, mais j&rsquo;aimerais l&rsquo;approfondir. Dans cet article, j&rsquo;aborde les points suivants\u00a0: 1. La kin\u00e9sith\u00e9rapie ne fonctionne-t-elle r\u00e9ellement pas chez votre patient ? et 2. Comment pouvez-vous am\u00e9liorer l&rsquo;alliance th\u00e9rapeutique et l&rsquo;adh\u00e9sion de vos patients afin de r\u00e9duire la probabilit\u00e9 que la kin\u00e9sith\u00e9rapie \u00e9choue\u00a0?<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>La kin\u00e9sith\u00e9rapie ne fonctionne-t-elle r\u00e9ellement pas chez votre patient ?<\/strong><\/h4>\n<p class=\"text\">Il peut \u00eatre facile de penser que votre patient ne va pas mieux lorsque sa douleur n&rsquo;a pas chang\u00e9 depuis une ou deux s\u00e9ances. Mais avant de c\u00e9der \u00e0 la panique, il convient de se pencher sur les points suivants :<\/p>\n<p class=\"text\" style=\"padding-top: 18px;\"><span style=\"text-decoration: underline;\">1) Des attentes et des objectifs r\u00e9alistes ont-ils \u00e9t\u00e9 fix\u00e9s ?<\/span><\/p>\n<p class=\"text\">Ce qui peut \u00eatre difficile, c\u2019est de faire face \u00e0 des patients qui ne seront satisfaits que s\u2019ils obtiennent une gu\u00e9rison compl\u00e8te d\u00e8s le premier jour. Or, tout comme nous attendons d\u2019un m\u00e9decin qu\u2019il nous donne des attentes r\u00e9alistes concernant les suites d\u2019une infiltration ou d\u2019une chirurgie, il est pr\u00e9f\u00e9rable de faire preuve de pragmatisme d\u00e8s le d\u00e9part plut\u00f4t que d&rsquo;avoir des patients d\u00e9\u00e7us par la suite. Ce que je dis aux patients dans la plupart des cas, c\u2019est, \u00ab je ne peux pas garantir que vous n&rsquo;aurez plus de douleur et que vous serez compl\u00e8tement r\u00e9tabli, \u00e9tant donn\u00e9 que la douleur persiste depuis un certain temps, mais je pense que vous constaterez une am\u00e9lioration significative des sympt\u00f4mes et de la fonction \u00bb.<\/p>\n<p class=\"text\" style=\"padding-top: 18px;\"><span style=\"text-decoration: underline;\">2) Les d\u00e9lais sont-ils r\u00e9alistes ?<\/span><\/p>\n<p class=\"text\">Pour certaines pathologies, il faut compter au moins un an pour obtenir une gu\u00e9rison compl\u00e8te, voire une am\u00e9lioration significative des sympt\u00f4mes. Cela peut \u00eatre tr\u00e8s difficile \u00e0 accepter pour les patients, mais il faut \u00eatre r\u00e9aliste, sinon certains patients risquent d&rsquo;abandonner le traitement s&rsquo;ils ne sont pas \u00ab\u00a0r\u00e9tablis\u00a0\u00bb en une ou trois visites.<\/p>\n<p class=\"text\">Cela dit, il faut \u00e9galement pr\u00e9voir des d\u00e9lais pour constater de petites am\u00e9liorations progressives en cours de route. D&rsquo;apr\u00e8s les donn\u00e9es disponibles et mon exp\u00e9rience, ces d\u00e9lais peuvent g\u00e9n\u00e9ralement varier :<\/p>\n<ul>\n<li>Amplitude de mouvement : principalement d&rsquo;une s\u00e9ance \u00e0 l&rsquo;autre<\/li>\n<li>Force : de 2-3 semaines \u00e0 1-3 mois<\/li>\n<li>Douleur : de 1 \u00e0 2 s\u00e9ances \u00e0 plusieurs mois (ou plus).<\/li>\n<\/ul>\n<p class=\"text\">Il est essentiel de fixer des objectifs plus petits en cours de route et de pr\u00e9voir des p\u00e9riodes d\u00e9termin\u00e9es pour les mesurer afin de continuer \u00e0 encourager les avanc\u00e9es du patient tout au long du processus.<\/p>\n<p class=\"aligncentre\"><a href=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-685868344-scaled-e1631529450187.jpg\" class=\"js-single-image-lightbox\"><img decoding=\"async\" src=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-685868344-scaled-e1631529450187.jpg\" alt=\"image\"><\/a><\/p>\n<p class=\"text\" style=\"padding-top: 18px;\"><span style=\"text-decoration: underline;\">3) Vous int\u00e9ressez-vous \u00e0 la fonction ou seulement aux sympt\u00f4mes ?<\/span><\/p>\n<p class=\"text\">Soyons r\u00e9alistes : nombreux sont ceux qui consid\u00e8rent la toute puissante \u00e9chelle de douleur et le nombre de patients sans douleur comme les principaux (voire les seuls) indicateurs de r\u00e9ussite. Cette attitude peut toutefois s&rsquo;av\u00e9rer tr\u00e8s r\u00e9ductrice, en particulier pour les patients qui se remettent d&rsquo;une longue pathologie.<\/p>\n<p class=\"text\">Il est assez courant, en particulier dans les cas chroniques, de constater des am\u00e9liorations fonctionnelles (c&rsquo;est-\u00e0-dire une am\u00e9lioration de la force, de la tol\u00e9rance \u00e0 l&rsquo;activit\u00e9) avant d&rsquo;obtenir des am\u00e9liorations significatives de la douleur. Cet aspect doit \u00e9galement \u00eatre mentionn\u00e9 et mesur\u00e9. Il est \u00e9galement important de mentionner que certains patients n&rsquo;ont pas de limitations fonctionnelles et souhaitent simplement que leur douleur diminue. Cela ne pose pas de probl\u00e8me tant que les objectifs sont r\u00e9alistes.<\/p>\n<p class=\"text\">Avant de paniquer, prenez le temps de r\u00e9fl\u00e9chir aux aspects mentionn\u00e9s ci-dessus, et vous vous rendrez peut-\u00eatre compte que vos patients sont plus sur la bonne voie que vous ne le pensez.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Que se passe-t-il si j&rsquo;ai fix\u00e9 des objectifs, des attentes et des d\u00e9lais r\u00e9alistes et que mon patient ne va toujours pas mieux ?<\/strong><\/h4>\n<p class=\"text\" style=\"padding-top: 18px;\">La question \u00e0 1 million d&rsquo;euros est la suivante : le patient respecte-t-il le plan de traitement ?<\/p>\n<p class=\"text\" style=\"padding-top: 18px;\"><span style=\"text-decoration: underline;\">Option A &#8211; Il ne respecte pas le plan<\/span><\/p>\n<p class=\"text\">De nombreux facteurs peuvent \u00eatre \u00e0 l&rsquo;origine de cette situation, notamment :<\/p>\n<p class=\"text\"><strong>1) Une mauvaise alliance th\u00e9rapeutique<\/strong><\/p>\n<p class=\"text\">Cela peut \u00eatre li\u00e9 \u00e0 un manque de confiance du patient envers le th\u00e9rapeute, \u00e0 un manque de confiance du th\u00e9rapeute en lui-m\u00eame, et\/ou au fait que le patient se sente bouscul\u00e9, rejet\u00e9 ou ignor\u00e9. Malheureusement, la nature de la pratique clinique peut parfois contribuer \u00e0 ce dernier point. Il est essentiel de ralentir, d&rsquo;\u00e9couter r\u00e9ellement le patient et d&rsquo;avoir l&rsquo;air s\u00fbr de soi.<\/p>\n<p class=\"text\"><strong>2) L&rsquo;approche th\u00e9rapeutique ne correspond pas aux objectifs et aux attentes du patient<\/strong><\/p>\n<p class=\"text\">Les patients doivent comprendre le \u00ab pourquoi \u00bb des traitements et la mani\u00e8re dont ils correspondent \u00e0 leurs objectifs. J&rsquo;aime que les patients me demandent pourquoi ils font certains exercices ou l&rsquo;utilit\u00e9 de certaines techniques de th\u00e9rapie manuelle, car cela me permet d&rsquo;aligner mon travail avec leurs objectifs. Si les patients ne comprennent pas le \u00ab\u00a0pourquoi\u00a0\u00bb, il faut s&rsquo;attendre \u00e0 ce qu&rsquo;ils n&rsquo;adh\u00e8rent pas au traitement.<\/p>\n<p class=\"text\">Il est essentiel d&rsquo;avoir des attentes r\u00e9alistes en ce qui concerne le r\u00e9sultat final, mais aussi en ce qui concerne le processus. Si un patient arrive en s&rsquo;attendant \u00e0 recevoir des ultrasons, du laser et de l&rsquo;acupuncture, mais qu&rsquo;il se retrouve avec de l&rsquo;exercice, une sensibilisation aux sciences de la douleur et des recommandations pour changer de mode de vie, cela posera un gros probl\u00e8me. Il faut faire des compromis (dans la limite du raisonnable) et informer le patient de ce qui est dans son int\u00e9r\u00eat. Est-ce si grave que cela de donner au patient cinq minutes de traitement passif si l&rsquo;on peut aussi lui proposer de l&rsquo;exercice, de l&rsquo;\u00e9ducation, du r\u00e9confort et des strat\u00e9gies d&rsquo;autogestion ?<\/p>\n<p class=\"text\">Comme l&rsquo;explique Mike Studer dans sa Masterclass sur l&rsquo;\u00e9conomie comportementale et les techniques psychologiques (lien <a href=\"https:\/\/www.physio-network.com\/masterclass\/the-missing-link-in-patient-engagement-behavioural-economics-and-psychologically-informed-techniques\/\">ici<\/a>), il faut parfois donner au patient ce qu&rsquo;il veut pour pouvoir lui donner ce dont il a besoin.<\/p>\n<p class=\"text\"><strong>3) Le programme ne correspond pas au mode de vie du patient<\/strong><\/p>\n<p class=\"text\">Bien que je sois avant tout un kin\u00e9sith\u00e9rapeute ax\u00e9 sur l&rsquo;exercice et l&rsquo;\u00e9ducation, je suis stup\u00e9fait lorsque je re\u00e7ois un patient qui a consult\u00e9 un autre kin\u00e9sith\u00e9rapeute qui lui a donn\u00e9 dix exercices sans que le patient ait eu son mot \u00e0 dire. Pour la plupart des patients non op\u00e9r\u00e9s et non fractur\u00e9s, je suis partisan de 1 \u00e0 3 exercices cibl\u00e9s qui sont faciles \u00e0 int\u00e9grer (c&rsquo;est-\u00e0-dire qui peuvent \u00eatre faits assis ou debout, sans \u00e9quipement sophistiqu\u00e9).<\/p>\n<p class=\"text\">Par exemple, une fente ou un <em>split squat<\/em> avec un contr\u00f4le excentrique renforce les fessiers et \u00e9tire les fl\u00e9chisseurs de hanche sans qu&rsquo;il soit n\u00e9cessaire de faire deux exercices distincts.<\/p>\n<p class=\"text\">Cela va dans le sens de la Masterclass de Mike Studer mentionn\u00e9e ci-dessus, et bien que cela ne soit pas toujours parfait, les exercices devraient \u00eatre relativement pratiques dans la mesure du possible.<\/p>\n<p class=\"aligncentre\"><a href=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-1210548146-scaled-e1631529499808.jpg\" class=\"js-single-image-lightbox\"><img decoding=\"async\" src=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-1210548146-scaled-e1631529499808.jpg\" alt=\"image\"><\/a><\/p>\n<p class=\"text\">Les th\u00e9rapeutes et les patients doivent collaborer \u00e9troitement. J&rsquo;essaie toujours de demander si c&rsquo;est \u00ab\u00a0trop ou pas assez\u00a0\u00bb lorsque je fais des exercices le premier jour.<\/p>\n<p class=\"text\">Il est \u00e9galement important de comprendre que certains patients ne sont pas toujours en mesure, du point de vue de leur mode de vie, de s&rsquo;engager \u00e0 suivre un programme de kin\u00e9sith\u00e9rapie. Si un patient est occup\u00e9 par un travail physique ou un sport qui aggrave ses sympt\u00f4mes et qu&rsquo;il n&rsquo;a pas le temps ou l&rsquo;\u00e9nergie de faire des exercices, il sera beaucoup plus difficile d&rsquo;obtenir un r\u00e9sultat positif. Certains ne seront peut-\u00eatre pas d&rsquo;accord, mais je pr\u00e9f\u00e8re \u00eatre franc avec les attentes plut\u00f4t que de voir un patient (et un th\u00e9rapeute) perdre du temps et de l&rsquo;argent pour n&rsquo;aboutir \u00e0 rien.<\/p>\n<p class=\"text\"><strong>4) Est-ce intol\u00e9rable ou trop facile ?<\/strong><\/p>\n<p class=\"text\">Parfois, vous ne pourrez pas \u00e9viter la douleur avec vos patients, mais si un patient revient et dit qu&rsquo;il a eu une pouss\u00e9e pendant deux jours apr\u00e8s avoir essay\u00e9 les exercices, vous devrez peut-\u00eatre faire quelques ajustements pour qu&rsquo;il reste sur la bonne voie et que les sympt\u00f4mes restent dans une fourchette acceptable.<\/p>\n<p class=\"text\">Il arrive que certains patients soient irrit\u00e9s par tout ce qu&rsquo;ils font, quelle que soit la quantit\u00e9 d&rsquo;exercices qu&rsquo;ils effectuent ou la douceur avec laquelle ils les effectuent. Je n&rsquo;aime pas entendre les patients se dire \u00ab j&rsquo;ai trop mal pour faire de la kin\u00e9 aujourd&rsquo;hui \u00bb, mais si un patient est hypersensible, qu&rsquo;il s&rsquo;enflamme facilement et qu&rsquo;il pr\u00e9sente des facteurs psychosociaux, il se peut qu&rsquo;il faille d&rsquo;abord s&rsquo;attaquer \u00e0 ces facteurs avant que la th\u00e9rapie ne soit efficace.<\/p>\n<p class=\"text\">\u00c0 l&rsquo;inverse, un programme de r\u00e9\u00e9ducation peut \u00eatre trop facile et le patient peut ne pas y adh\u00e9rer, ou il peut ne pas \u00eatre suffisant pour pr\u00e9parer le patient \u00e0 des activit\u00e9s physiquement exigeantes. Par exemple, des ponts fessiers de base ne permettront pas \u00e0 un patient souffrant d&rsquo;une \u00e9longation ou d&rsquo;une tendinopathie des ischio-jambiers de reprendre le sprint ou la gymnastique.<\/p>\n<p class=\"aligncentre\"><a href=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-504247240-scaled-e1631529515943.jpg\" class=\"js-single-image-lightbox\"><img decoding=\"async\" src=\"https:\/\/www.physio-network.com\/wp-content\/uploads\/2021\/09\/iStock-504247240-scaled-e1631529515943.jpg\" alt=\"image\"><\/a><\/p>\n<p class=\"text\" style=\"padding-top: 18px;\"><span style=\"text-decoration: underline;\">Option\u00a0B \u2013 Le patient respecte le plan de traitement<\/span><\/p>\n<p class=\"text\">Dans ce cas\u00a0:<\/p>\n<p class=\"text\"><strong>1) Le traitement est-il en ad\u00e9quation avec les objectifs du patient\u00a0?<\/strong><\/p>\n<p class=\"text\">Am\u00e9liorer l&rsquo;amplitude de mouvement de l&rsquo;\u00e9paule est une bonne chose, mais si l&rsquo;objectif de la patiente est de pouvoir porter son enfant, elle n&rsquo;a probablement pas besoin d&rsquo;une flexion et d&rsquo;une abduction de l&rsquo;\u00e9paule \u00e0 180 degr\u00e9s. L&rsquo;accent doit \u00eatre mis davantage sur la force et la tol\u00e9rance \u00e0 la charge.<\/p>\n<p class=\"text\"><strong>2) Est-ce trop difficile \/ trop facile \/ trop douloureux\u00a0?<\/strong><\/p>\n<p class=\"text\">M\u00eame principe que ci-dessus !<\/p>\n<p class=\"text\"><em>*Note &#8211; avant d&rsquo;aborder les deux points suivants, il est essentiel pour moi de partager la Masterclass de Tim Mitchell intitul\u00e9e \u00ab\u00a0Un plan pour optimiser l&rsquo;interrogatoire du patient et les r\u00e9sultats cliniques\u00a0\u00bb (<a href=\"https:\/\/www.physio-network.com\/masterclass\/a-framework-for-optimising-the-patient-interview-clinical-outcomes\/\">lien ici<\/a>), car une grande partie de ce qui est couvert dans cette Masterclass se rapporte aux points 3 et 4 ci-dessous.<\/em><\/p>\n<p class=\"text\"><strong>3) Le diagnostic est-il correct ?<\/strong><\/p>\n<p class=\"text\">Il arrive que d&rsquo;autres diagnostics passent inaper\u00e7us. Cela arrive de temps en temps et cela m&rsquo;est arriv\u00e9. J&rsquo;ai eu un patient chez qui on soup\u00e7onnait une hernie discale, qui a commenc\u00e9 \u00e0 r\u00e9gresser et chez qui on a diagnostiqu\u00e9 plus tard (par imagerie) un kyste qui n\u00e9cessitait une prise en charge m\u00e9dicale. Bien que je ne sois pas partisan d&rsquo;une utilisation excessive de l&rsquo;imagerie, celle-ci a sa place, en particulier si le patient r\u00e9gresse ou si les choses ne semblent pas claires.<\/p>\n<p class=\"text\">Il y a aussi des cas, et cela m&rsquo;est arriv\u00e9 plusieurs fois au cours de ma carri\u00e8re, o\u00f9 un r\u00e9sultat d&rsquo;imagerie significatif (par exemple, un corps \u00e9tranger, un ligament d\u00e9chir\u00e9) appara\u00eet \u00e0 l&rsquo;IRM alors que tous les tests orthop\u00e9diques que vous avez effectu\u00e9s pour ces indications se sont r\u00e9v\u00e9l\u00e9s n\u00e9gatifs. Les tests orthop\u00e9diques (m\u00eame lorsqu&rsquo;ils sont regroup\u00e9s en cluster) et les ant\u00e9c\u00e9dents cliniques ne sont pas parfaits.<\/p>\n<p class=\"text\">Par ailleurs, appelons un chat un chat &#8211; les pr\u00e9sentations de cas sont parfois incoh\u00e9rentes d&rsquo;une s\u00e9ance \u00e0 l&rsquo;autre et ne rentrent pas toujours dans une bo\u00eete bien ordonn\u00e9e. Cela peut \u00eatre tr\u00e8s frustrant lorsque les patients pr\u00e9sentent ce que j&rsquo;appelle le \u00ab syndrome de la cible mobile \u00bb, o\u00f9 les sympt\u00f4mes se d\u00e9placent et o\u00f9 les tests qui peuvent \u00eatre douloureux ou non douloureux lors d&rsquo;une s\u00e9ance peuvent \u00eatre invers\u00e9s lors de la s\u00e9ance suivante. Ce probl\u00e8me peut \u00e9galement se poser chez les patients qui pr\u00e9sentent de nombreux facteurs psychosociaux et\/ou des comportements douloureux et qui, de ce fait, pr\u00e9sentent des signes qui ne sont pas physiques.<\/p>\n<p class=\"text\"><strong>4) Existe-t-il d&rsquo;autres obstacles ?<\/strong><\/p>\n<p class=\"text\">L&rsquo;une des principales raisons pour lesquelles j&rsquo;ai vu des patients actifs \u00e9chouer en kin\u00e9sith\u00e9rapie avec d&rsquo;autres praticiens est le manque d&rsquo;attention port\u00e9e \u00e0 ce qui se fait en dehors de la clinique. Si les douleurs cervicales de vos patients sont aggrav\u00e9es par 10 heures de travail de bureau ou si la tendinopathie des ischio-jambiers de vos patients est aggrav\u00e9e par d&rsquo;innombrables kilom\u00e8tres de course \u00e0 pied, mais que rien n&rsquo;est dit ou fait pour modifier l&rsquo;activit\u00e9, vous et vos patients risquez de vous retrouver au pied du mur sans avoir progress\u00e9.<\/p>\n<p class=\"text\">Parfois, les activit\u00e9s ne sont pas modifiables et c&rsquo;est normal, mais comme nous l&rsquo;avons dit plus haut, il faut se fixer des objectifs et des d\u00e9lais r\u00e9alistes et les red\u00e9finir si n\u00e9cessaire.<br \/>\nIl peut \u00e9galement y avoir une myriade de facteurs de sant\u00e9 physique (diab\u00e8te, tabagisme, ob\u00e9sit\u00e9) ainsi que des facteurs psychosociaux. Certaines comorbidit\u00e9s physiques et psychosociales peuvent n\u00e9cessiter l&rsquo;intervention d&rsquo;autres professionnels de sant\u00e9, en fonction de votre champ de comp\u00e9tence et de votre libert\u00e9 d&rsquo;action. Je dis aux patients pr\u00e9sentant des pathologies complexes que la kin\u00e9sith\u00e9rapie ne peut traiter qu&rsquo;une partie du g\u00e2teau et que c&rsquo;est la raison pour laquelle je ne peux pas toujours garantir que les patients ne souffriront plus \u00e0 l&rsquo;issue de la r\u00e9\u00e9ducation.<\/p>\n<p class=\"text\">Je regroupe les facteurs psychologiques, et oui, c&rsquo;est tr\u00e8s simplifi\u00e9, en deux cat\u00e9gories : ceux qui rel\u00e8vent du champ d&rsquo;application de la kin\u00e9sith\u00e9rapie et ceux qui n&rsquo;en rel\u00e8vent pas (du moins l\u00e0 o\u00f9 je travaille).<\/p>\n<p>&nbsp;<\/p>\n<p class=\"text\"><em>*Notez que certains de ces \u00e9l\u00e9ments peuvent varier en fonction du contexte. Par exemple, la d\u00e9pression due \u00e0 l&rsquo;inactivit\u00e9 caus\u00e9e par la douleur peut certainement entrer dans notre champ d&rsquo;application, alors que la d\u00e9pression due \u00e0 la perte d&rsquo;un \u00eatre cher n&rsquo;entre absolument pas dans notre champ d&rsquo;application.<\/em><\/p>\n<p class=\"text\">Et il peut y avoir des obstacles qui ne peuvent \u00eatre surmont\u00e9s. L&rsquo;un d&rsquo;entre eux, que j&rsquo;ai pu observer \u00e0 l&rsquo;\u00e9poque o\u00f9 je m&rsquo;occupais de dossiers complexes d&rsquo;indemnisation des accidents du travail, est celui des obstacles li\u00e9s au lieu de travail. Bien que certaines strat\u00e9gies soient mises en place pour faciliter le r\u00e9tablissement et le retour au travail, elles peuvent encore compromettre les r\u00e9sultats th\u00e9rapeutiques.<\/p>\n<p class=\"text\">Avant de poursuivre, il est \u00e9galement important de noter que, parfois, les patients ne pensent pas toujours \u00e0 parler ou ne se sentent pas \u00e0 l&rsquo;aise pour parler au th\u00e9rapeute de certains facteurs qui peuvent avoir des r\u00e9percussions \u00e0 l&rsquo;avenir. Un exemple est celui d&rsquo;une de mes patientes qui souffrait de douleurs au coccyx apr\u00e8s son accouchement. Au cours de l&rsquo;accouchement, il y a eu des complications majeures ainsi qu&rsquo;un traumatisme physique et psychosocial. Cela ne change pas n\u00e9cessairement la r\u00e9\u00e9ducation effectu\u00e9e, mais cela peut n\u00e9cessiter une \u00ab r\u00e9initialisation des objectifs \u00bb ainsi que l&rsquo;orientation vers des professionnels de sant\u00e9 mentale.<\/p>\n<p class=\"text\">Comme Tim l&rsquo;explique dans sa Masterclass sur l&rsquo;interrogatoire clinique, il est important d&rsquo;acqu\u00e9rir une compr\u00e9hension tr\u00e8s compl\u00e8te de tous les diff\u00e9rents facteurs bio-psycho-sociaux qui peuvent contribuer \u00e0 la situation clinique et \u00e0 la description d&rsquo;un patient, car le traitement doit \u00eatre orient\u00e9 en fonction de ces facteurs. Par exemple, un protocole de traitement bas\u00e9 essentiellement sur les tissus ne sera pas tr\u00e8s efficace pour une patiente qui a d&rsquo;importants probl\u00e8mes psychosociaux et d&rsquo;\u00e9vitement, ainsi que des facteurs majeurs li\u00e9s au mode de vie qui contribuent \u00e0 sa douleur. Si vous constatez que vous n&rsquo;avancez pas, malgr\u00e9 une bonne observance, il est important de s&rsquo;assurer que vous n&rsquo;avez pas oubli\u00e9 certains \u00e9l\u00e9ments.<\/p>\n<p class=\"text\"><strong>5) Les patients sont parfois des candidats \u00e0 la chirurgie<\/strong><\/p>\n<p class=\"text\">Si un patient pr\u00e9sente des sympt\u00f4mes qui correspondent \u00e0 l&rsquo;imagerie, s&rsquo;il n&rsquo;y a pas d&rsquo;obstacles majeurs \u00e0 un bon r\u00e9sultat chirurgical et s&rsquo;il a b\u00e9n\u00e9fici\u00e9 d&rsquo;une bonne th\u00e9rapie, je suis favorable \u00e0 la chirurgie.<\/p>\n<p class=\"text\"><strong>6) Et parfois, en toute franchise, la kin\u00e9sith\u00e9rapie (m\u00eame lorsqu&rsquo;elle est bien faite) ne fonctionne tout simplement pas !<\/strong><\/p>\n<p class=\"text\" style=\"padding-top: 18px;\">J&rsquo;esp\u00e8re que ce blog vous a donn\u00e9 quelques conseils utiles pour am\u00e9liorer votre alliance th\u00e9rapeutique, l&rsquo;adh\u00e9sion des patients et les r\u00e9sultats afin de minimiser le nombre de vos prises en charge qui \u00e9chouent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00e9but d&rsquo;ann\u00e9e, j&rsquo;ai lu un excellent travail d&rsquo;Adam Meakins sur le concept d&rsquo;\u00e9chec des patients en kin\u00e9sith\u00e9rapie (1). Ce travail \u00e9tait excellent, mais j&rsquo;aimerais&#8230;<\/p>\n","protected":false},"author":8660,"featured_media":13217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[544],"tags":[],"class_list":["post-13208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autre"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/posts\/13208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/users\/8660"}],"replies":[{"embeddable":true,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/comments?post=13208"}],"version-history":[{"count":8,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/posts\/13208\/revisions"}],"predecessor-version":[{"id":13220,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/posts\/13208\/revisions\/13220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/media\/13217"}],"wp:attachment":[{"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/media?parent=13208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/categories?post=13208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.physio-network.com\/fr\/wp-json\/wp\/v2\/tags?post=13208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}